{"id":529,"date":"2020-06-16T09:45:09","date_gmt":"2020-06-16T17:45:09","guid":{"rendered":"http:\/\/kpbsdschools.local\/?page_id=529"},"modified":"2020-12-04T11:59:14","modified_gmt":"2020-12-04T20:59:14","slug":"about","status":"publish","type":"page","link":"https:\/\/kpbsd.org\/schools\/nikiski-middle-high\/about\/","title":{"rendered":"About"},"content":{"rendered":"\n<h4 class=\"has-text-align-center wp-block-heading\"><em>Did you know?<\/em><\/h4>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column blue-box col-pad is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"has-text-align-center wp-block-heading\">**<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column red-box col-pad is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"has-text-align-center wp-block-heading\">**<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column yellow-box col-pad is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"has-text-align-center wp-block-heading\">**<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column green-box col-pad is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"has-text-align-center wp-block-heading\">**<\/h2>\n\n\n\n<p><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-2 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:80%\">\n<div class=\"wp-block-pb-accordion-item c-accordion__item js-accordion-item no-js\" data-initially-open=\"false\" data-click-to-close=\"true\" data-auto-close=\"false\" data-scroll=\"false\" data-scroll-offset=\"0\"><h2 id=\"at-59617\" class=\"c-accordion__title js-accordion-controller\" role=\"button\">About our Classrooms<\/h2><div id=\"ac-59617\" class=\"c-accordion__content\">\n<p>All our classrooms go through Canvas whether we are in remote or in-person status.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-pb-accordion-item c-accordion__item js-accordion-item no-js\" data-initially-open=\"false\" data-click-to-close=\"true\" data-auto-close=\"true\" data-scroll=\"false\" data-scroll-offset=\"0\"><h2 id=\"at-3927\" class=\"c-accordion__title js-accordion-controller\" role=\"button\">FAQs<\/h2><div id=\"ac-3927\" class=\"c-accordion__content\">\n<p><strong>What grades attend Nikiski Middle\/High School<\/strong>?<\/p>\n\n\n\n<p>Grades 6-12<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-pb-accordion-item c-accordion__item js-accordion-item no-js\" data-initially-open=\"false\" data-click-to-close=\"true\" data-auto-close=\"true\" data-scroll=\"false\" data-scroll-offset=\"0\"><h2 id=\"at-48750\" class=\"c-accordion__title js-accordion-controller\" role=\"button\">School Enrollment Info<\/h2><div id=\"ac-48750\" class=\"c-accordion__content\">\n<p><a href=\"https:\/\/www.kpbsd.k12.ak.us\/students_parents.aspx?id=470\">Link to Student Registration Page<\/a><\/p>\n\n\n\n<p>Contact the school at 907-776-9400<\/p>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<h2 class=\"wp-block-heading\">Sub-Navigation<\/h2>\n\n\n<ul class=\"list-pages-shortcode child-pages\"><li class=\"page_item page-item-547\"><a href=\"https:\/\/kpbsd.org\/schools\/nikiski-middle-high\/about\/office\/\">Office<\/a><\/li>\n<li class=\"page_item page-item-661\"><a href=\"https:\/\/kpbsd.org\/schools\/nikiski-middle-high\/about\/site-council\/\">Site Council<\/a><\/li>\n<li class=\"page_item page-item-757\"><a href=\"https:\/\/kpbsd.org\/schools\/nikiski-middle-high\/about\/nikiski-middle-high-school-bylaws\/\">NMHS Bylaws- SITE COUNCIL<\/a><\/li>\n<li class=\"page_item page-item-123\"><a href=\"https:\/\/kpbsd.org\/schools\/nikiski-middle-high\/about\/library\/\">Library<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Did you know? ** ** ** ** Sub-Navigation<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-529","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/kpbsd.org\/schools\/nikiski-middle-high\/wp-json\/wp\/v2\/pages\/529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kpbsd.org\/schools\/nikiski-middle-high\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kpbsd.org\/schools\/nikiski-middle-high\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kpbsd.org\/schools\/nikiski-middle-high\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kpbsd.org\/schools\/nikiski-middle-high\/wp-json\/wp\/v2\/comments?post=529"}],"version-history":[{"count":3,"href":"https:\/\/kpbsd.org\/schools\/nikiski-middle-high\/wp-json\/wp\/v2\/pages\/529\/revisions"}],"predecessor-version":[{"id":3454,"href":"https:\/\/kpbsd.org\/schools\/nikiski-middle-high\/wp-json\/wp\/v2\/pages\/529\/revisions\/3454"}],"wp:attachment":[{"href":"https:\/\/kpbsd.org\/schools\/nikiski-middle-high\/wp-json\/wp\/v2\/media?parent=529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}