{"id":12540,"date":"2026-04-13T16:05:35","date_gmt":"2026-04-14T00:05:35","guid":{"rendered":"https:\/\/kpbsd.org\/schools\/river-city-academy\/event\/vacation-day-possible-make-up-day\/"},"modified":"2026-05-08T18:55:23","modified_gmt":"2026-05-09T02:55:23","slug":"vacation-day-possible-make-up-day","status":"publish","type":"tribe_events","link":"https:\/\/kpbsd.org\/schools\/river-city-academy\/event\/vacation-day-possible-make-up-day\/","title":{"rendered":"Vacation Day \/ Possible Make Up Day"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"tags":[],"tribe_events_cat":[6],"class_list":["post-12540","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-districtwide-calendar","cat_districtwide-calendar"],"_links":{"self":[{"href":"https:\/\/kpbsd.org\/schools\/river-city-academy\/wp-json\/wp\/v2\/tribe_events\/12540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kpbsd.org\/schools\/river-city-academy\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/kpbsd.org\/schools\/river-city-academy\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/kpbsd.org\/schools\/river-city-academy\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kpbsd.org\/schools\/river-city-academy\/wp-json\/wp\/v2\/comments?post=12540"}],"version-history":[{"count":1,"href":"https:\/\/kpbsd.org\/schools\/river-city-academy\/wp-json\/wp\/v2\/tribe_events\/12540\/revisions"}],"predecessor-version":[{"id":12597,"href":"https:\/\/kpbsd.org\/schools\/river-city-academy\/wp-json\/wp\/v2\/tribe_events\/12540\/revisions\/12597"}],"wp:attachment":[{"href":"https:\/\/kpbsd.org\/schools\/river-city-academy\/wp-json\/wp\/v2\/media?parent=12540"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kpbsd.org\/schools\/river-city-academy\/wp-json\/wp\/v2\/tags?post=12540"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/kpbsd.org\/schools\/river-city-academy\/wp-json\/wp\/v2\/tribe_events_cat?post=12540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}